{"id":7716,"count":31,"description":"","link":"https:\/\/blackbeltwhitehat.com\/en\/category\/boxing\/","name":"boxing","slug":"boxing","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>boxing Archives - Fitness &amp; MMA Blog - BlackBeltWhiteHat.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blackbeltwhitehat.com\/en\/category\/boxing\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"boxing Archives - Fitness &amp; MMA Blog - BlackBeltWhiteHat.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blackbeltwhitehat.com\/en\/category\/boxing\/\" \/>\n<meta property=\"og:site_name\" content=\"Fitness &amp; MMA Blog - BlackBeltWhiteHat.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MMATraining1980\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"boxing Archives - Fitness &amp; MMA Blog - BlackBeltWhiteHat.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blackbeltwhitehat.com\/en\/category\/boxing\/","og_locale":"en_GB","og_type":"article","og_title":"boxing Archives - Fitness &amp; MMA Blog - BlackBeltWhiteHat.com","og_url":"https:\/\/blackbeltwhitehat.com\/en\/category\/boxing\/","og_site_name":"Fitness &amp; MMA Blog - BlackBeltWhiteHat.com","twitter_card":"summary_large_image","twitter_site":"@MMATraining1980","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blackbeltwhitehat.com\/category\/boxing\/","url":"https:\/\/blackbeltwhitehat.com\/category\/boxing\/","name":"boxing Archives - Fitness &amp; MMA Blog - BlackBeltWhiteHat.com","isPartOf":{"@id":"https:\/\/blackbeltwhitehat.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/blackbeltwhitehat.com\/category\/boxing\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/blackbeltwhitehat.com\/category\/boxing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blackbeltwhitehat.com\/"},{"@type":"ListItem","position":2,"name":"boxing"}]},{"@type":"WebSite","@id":"https:\/\/blackbeltwhitehat.com\/en\/#website","url":"https:\/\/blackbeltwhitehat.com\/en\/","name":"Fitness & MMA Blog - BlackBeltWhiteHat.com","description":"Fitness, MMA and Nutrition Blog UK","publisher":{"@id":"https:\/\/blackbeltwhitehat.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blackbeltwhitehat.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/blackbeltwhitehat.com\/en\/#organization","name":"Fitness & MMA Blog - BlackBeltWhiteHat.com","url":"https:\/\/blackbeltwhitehat.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/blackbeltwhitehat.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/blackbeltwhitehat.com\/wp-content\/uploads\/2019\/06\/cropped-mmabloglogodis-copy.png","contentUrl":"https:\/\/blackbeltwhitehat.com\/wp-content\/uploads\/2019\/06\/cropped-mmabloglogodis-copy.png","width":352,"height":352,"caption":"Fitness & MMA Blog - BlackBeltWhiteHat.com"},"image":{"@id":"https:\/\/blackbeltwhitehat.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BlackBeltWhiteHat\/","https:\/\/x.com\/MMATraining1980"]}]}},"_links":{"self":[{"href":"https:\/\/blackbeltwhitehat.com\/en\/wp-json\/wp\/v2\/categories\/7716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blackbeltwhitehat.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blackbeltwhitehat.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blackbeltwhitehat.com\/en\/wp-json\/wp\/v2\/posts?categories=7716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}