{"id":2328,"date":"2014-11-18T08:40:22","date_gmt":"2014-11-18T08:40:22","guid":{"rendered":"http:\/\/blackbeltwhitehat.com\/?p=2328"},"modified":"2014-11-18T08:40:22","modified_gmt":"2014-11-18T08:40:22","slug":"niveles-de-sentido-del-humor","status":"publish","type":"post","link":"https:\/\/blackbeltwhitehat.com\/es\/2014\/11\/18\/niveles-de-sentido-del-humor\/","title":{"rendered":"&#039;Niveles&#039; del sentido del humor\u2018"},"content":{"rendered":"<p><strong>Nivel 1<\/strong> \u2013 Eres un ni\u00f1o, simplemente te r\u00edes de las cosas porque son divertidas.<\/p>\n<p><strong>Nivel 2<\/strong> Eres un adolescente\/una persona miserable y c\u00ednica. Necesitas una raz\u00f3n para re\u00edrte de las cosas. &quot;\u00bfPor qu\u00e9 es gracioso?&quot; es tu frase favorita.<\/p>\n<p><strong>Nivel 3<\/strong> \u2013 Te das cuenta de que el nivel 2 es para idiotas y comienzas a disfrutar y re\u00edrte de nuevo de cosas sin ninguna justificaci\u00f3n l\u00f3gica.<\/p>\n<p>Usa tu sistema l\u00edmbico para el humor. No tu cerebro neomam\u00edfero.<\/p>","protected":false},"excerpt":{"rendered":"<p>Level 1 &#8211; You&#8217;re a kid, you just laugh at things because they are funny Level 2 &#8211; You&#8217;re a teenager\/miserable &amp; cynical person. You need a reason to laugh at things. \u00a0&#8220;Why is that funny?&#8221; is you&#8217;re favourite phrase. Level 3 &#8211; You realise that level 2 is for bellends, and just start enjoying [&hellip;]<\/p>\n","protected":false},"author":41980142,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Sense of Humour 'Levels'","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1868],"tags":[272,376,35],"class_list":["post-2328","post","type-post","status-publish","format-standard","hentry","category-philosophy","tag-fun","tag-humor","tag-humour"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sense of Humour &#039;Levels&#039; - Fitness &amp; MMA Blog - BlackBeltWhiteHat.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blackbeltwhitehat.com\/es\/2014\/11\/18\/niveles-de-sentido-del-humor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sense of Humour &#039;Levels&#039; - Fitness &amp; MMA Blog - BlackBeltWhiteHat.com\" \/>\n<meta property=\"og:description\" content=\"Level 1 &#8211; You&#8217;re a kid, you just laugh at things because they are funny Level 2 &#8211; You&#8217;re a teenager\/miserable &amp; cynical person. You need a reason to laugh at things. \u00a0&#8220;Why is that funny?&#8221; is you&#8217;re favourite phrase. Level 3 &#8211; You realise that level 2 is for bellends, and just start enjoying [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blackbeltwhitehat.com\/es\/2014\/11\/18\/niveles-de-sentido-del-humor\/\" \/>\n<meta property=\"og:site_name\" content=\"Fitness &amp; MMA Blog - BlackBeltWhiteHat.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BlackBeltWhiteHat\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-18T08:40:22+00:00\" \/>\n<meta name=\"author\" content=\"Dave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MMATraining1980\" \/>\n<meta name=\"twitter:site\" content=\"@MMATraining1980\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dave\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sense of Humour 'Levels' - Fitness &amp; MMA Blog - BlackBeltWhiteHat.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blackbeltwhitehat.com\/es\/2014\/11\/18\/niveles-de-sentido-del-humor\/","og_locale":"es_ES","og_type":"article","og_title":"Sense of Humour 'Levels' - Fitness &amp; MMA Blog - BlackBeltWhiteHat.com","og_description":"Level 1 &#8211; You&#8217;re a kid, you just laugh at things because they are funny Level 2 &#8211; You&#8217;re a teenager\/miserable &amp; cynical person. You need a reason to laugh at things. \u00a0&#8220;Why is that funny?&#8221; is you&#8217;re favourite phrase. Level 3 &#8211; You realise that level 2 is for bellends, and just start enjoying [&hellip;]","og_url":"https:\/\/blackbeltwhitehat.com\/es\/2014\/11\/18\/niveles-de-sentido-del-humor\/","og_site_name":"Fitness &amp; MMA Blog - BlackBeltWhiteHat.com","article_publisher":"https:\/\/www.facebook.com\/BlackBeltWhiteHat\/","article_published_time":"2014-11-18T08:40:22+00:00","author":"Dave","twitter_card":"summary_large_image","twitter_creator":"@MMATraining1980","twitter_site":"@MMATraining1980","twitter_misc":{"Escrito por":"Dave"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blackbeltwhitehat.com\/2014\/11\/18\/sense-of-humour-levels\/#article","isPartOf":{"@id":"https:\/\/blackbeltwhitehat.com\/2014\/11\/18\/sense-of-humour-levels\/"},"author":{"name":"Dave","@id":"https:\/\/blackbeltwhitehat.com\/en\/#\/schema\/person\/f009f75d478333ab9af4d98d1c2d03bd"},"headline":"Sense of Humour &#8216;Levels&#8217;","datePublished":"2014-11-18T08:40:22+00:00","mainEntityOfPage":{"@id":"https:\/\/blackbeltwhitehat.com\/2014\/11\/18\/sense-of-humour-levels\/"},"wordCount":78,"commentCount":0,"publisher":{"@id":"https:\/\/blackbeltwhitehat.com\/en\/#organization"},"keywords":["fun","humor","humour"],"articleSection":["Philosophy"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blackbeltwhitehat.com\/2014\/11\/18\/sense-of-humour-levels\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blackbeltwhitehat.com\/2014\/11\/18\/sense-of-humour-levels\/","url":"https:\/\/blackbeltwhitehat.com\/2014\/11\/18\/sense-of-humour-levels\/","name":"Sense of Humour 'Levels' - Fitness &amp; MMA Blog - BlackBeltWhiteHat.com","isPartOf":{"@id":"https:\/\/blackbeltwhitehat.com\/en\/#website"},"datePublished":"2014-11-18T08:40:22+00:00","breadcrumb":{"@id":"https:\/\/blackbeltwhitehat.com\/2014\/11\/18\/sense-of-humour-levels\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blackbeltwhitehat.com\/2014\/11\/18\/sense-of-humour-levels\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blackbeltwhitehat.com\/2014\/11\/18\/sense-of-humour-levels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blackbeltwhitehat.com\/"},{"@type":"ListItem","position":2,"name":"Sense of Humour &#8216;Levels&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/blackbeltwhitehat.com\/en\/#website","url":"https:\/\/blackbeltwhitehat.com\/en\/","name":"Blog de fitness y MMA - BlackBeltWhiteHat.com","description":"Blog de fitness, MMA y nutrici\u00f3n del Reino Unido","publisher":{"@id":"https:\/\/blackbeltwhitehat.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blackbeltwhitehat.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blackbeltwhitehat.com\/en\/#organization","name":"Blog de fitness y MMA - BlackBeltWhiteHat.com","url":"https:\/\/blackbeltwhitehat.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blackbeltwhitehat.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/blackbeltwhitehat.com\/wp-content\/uploads\/2019\/06\/cropped-mmabloglogodis-copy.png","contentUrl":"https:\/\/blackbeltwhitehat.com\/wp-content\/uploads\/2019\/06\/cropped-mmabloglogodis-copy.png","width":352,"height":352,"caption":"Fitness & MMA Blog - BlackBeltWhiteHat.com"},"image":{"@id":"https:\/\/blackbeltwhitehat.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BlackBeltWhiteHat\/","https:\/\/x.com\/MMATraining1980"]},{"@type":"Person","@id":"https:\/\/blackbeltwhitehat.com\/en\/#\/schema\/person\/f009f75d478333ab9af4d98d1c2d03bd","name":"Dave","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e84bb8dd328aa13877039998cc07d77b62f98c8100dba6c4acb436a41e2a08ac?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e84bb8dd328aa13877039998cc07d77b62f98c8100dba6c4acb436a41e2a08ac?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e84bb8dd328aa13877039998cc07d77b62f98c8100dba6c4acb436a41e2a08ac?s=96&d=identicon&r=g","caption":"Dave"},"description":"Explorador del norte de Gales","sameAs":["http:\/\/seoandmma.wordpress.com"],"url":"https:\/\/blackbeltwhitehat.com\/es\/author\/seoandmma\/"}]}},"jetpack_publicize_connections":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2Sx3t-By","jetpack-related-posts":[{"id":5981,"url":"https:\/\/blackbeltwhitehat.com\/es\/2016\/09\/30\/una-guia-para-hombres-sobre-el-presupuesto-de-una-boda\/","url_meta":{"origin":2328,"position":0},"title":"Gu\u00eda para hombres sobre el presupuesto de una boda","author":"Dave","date":"septiembre 30, 2016","format":false,"excerpt":"Don't get married \u00a0","rel":"","context":"En \u00abbudget\u00bb","block_context":{"text":"budget","link":"https:\/\/blackbeltwhitehat.com\/es\/etiqueta\/presupuesto\/"},"img":{"alt_text":"Nate Diaz Vape Pen","src":"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2016\/09\/nated.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2016\/09\/nated.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2016\/09\/nated.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":9093,"url":"https:\/\/blackbeltwhitehat.com\/es\/2018\/06\/22\/resumen-del-libro-de-los-5-anillos\/","url_meta":{"origin":2328,"position":1},"title":"El libro de los 5 anillos \u2013 Resumen","author":"Dave","date":"junio 22, 2018","format":false,"excerpt":"Nacido en el siglo XVI, cerca del final de la guerra civil japonesa, Miyamoto Musashi fue un samur\u00e1i n\u00f3mada que luch\u00f3 en pocas batallas, pero en decenas de duelos. Es conocido como el mejor espadach\u00edn de Jap\u00f3n. El libro ha tenido un enorme impacto en la cultura del este de Asia\u2026","rel":"","context":"En \u00abMMA\u00bb","block_context":{"text":"MMA","link":"https:\/\/blackbeltwhitehat.com\/es\/categoria\/artes-marciales-mixtas\/"},"img":{"alt_text":"mushashi","src":"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2018\/06\/mush.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2018\/06\/mush.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2018\/06\/mush.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2018\/06\/mush.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15728,"url":"https:\/\/blackbeltwhitehat.com\/es\/2025\/02\/04\/resena-de-now-foods-true-focus-2025\/","url_meta":{"origin":2328,"position":2},"title":"NOW FOODS True Focus Supplement Review [2025]","author":"Dave","date":"febrero 4, 2025","format":false,"excerpt":"Este es uno de mis suplementos nootr\u00f3picos favoritos. Contiene L-tirosina y fenilalanina, que aumentan los niveles de dopamina. Por esta raz\u00f3n, recomiendo tomarlo de forma c\u00edclica; no lo tomes a diario. Tambi\u00e9n puedes explorar maneras de regular tus niveles de dopamina\u2026","rel":"","context":"En \u00abNutrition\u00bb","block_context":{"text":"Nutrition","link":"https:\/\/blackbeltwhitehat.com\/es\/categoria\/nutricion\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/sZb3tjaaPt4\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6775,"url":"https:\/\/blackbeltwhitehat.com\/es\/2017\/05\/04\/potenciadores-naturales-de-testosterona\/","url_meta":{"origin":2328,"position":3},"title":"Potenciadores naturales de testosterona","author":"Dave","date":"mayo 4, 2017","format":false,"excerpt":"Well, if you don't want to inject testosterone enanthate in your glute, there are a few more options. From personal experience these supplements definitely make you feel stronger and increase sex drive, but the research around significant increases in testosterone levels is a little vague and sketchy on most of\u2026","rel":"","context":"En \u00abFitness\u00bb","block_context":{"text":"Fitness","link":"https:\/\/blackbeltwhitehat.com\/es\/categoria\/aptitud-fisica\/"},"img":{"alt_text":"test boosters","src":"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2016\/05\/pexels-photo-116078.jpeg?fit=940%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2016\/05\/pexels-photo-116078.jpeg?fit=940%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2016\/05\/pexels-photo-116078.jpeg?fit=940%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2016\/05\/pexels-photo-116078.jpeg?fit=940%2C628&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3177,"url":"https:\/\/blackbeltwhitehat.com\/es\/2015\/09\/30\/ronnie-pickering-furia-al-volante\/","url_meta":{"origin":2328,"position":4},"title":"El amor es la respuesta \u2013 Ronnie Pickering","author":"Dave","date":"septiembre 30, 2015","format":false,"excerpt":"Bueno, esto confirma que el amor es la respuesta, y que la ira y el odio son solo para idiotas. Ronnie Pickering es la personificaci\u00f3n del t\u00edpico brit\u00e1nico enfadado. Lo ves todos los d\u00edas en Facebook: gente quej\u00e1ndose, lament\u00e1ndose, enfad\u00e1ndose y culpando a los dem\u00e1s de sus 99 problemas del primer mundo\u2026","rel":"","context":"En \u00abPhilosophy\u00bb","block_context":{"text":"Philosophy","link":"https:\/\/blackbeltwhitehat.com\/es\/categoria\/filosofia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/r0dcv6GKNNw\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8359,"url":"https:\/\/blackbeltwhitehat.com\/es\/2017\/11\/02\/como-aumentar-los-niveles-de-energia\/","url_meta":{"origin":2328,"position":5},"title":"C\u00f3mo aumentar los niveles de energ\u00eda","author":"Dave","date":"noviembre 2, 2017","format":false,"excerpt":"\u00bfNo eres una persona ma\u00f1anera? \u00bfO prefieres la tarde? Espero que estos consejos te ayuden: 1. Ejercicios de respiraci\u00f3n: respiraciones profundas y poderosas. No me preguntes c\u00f3mo funciona, \u00a1simplemente funciona! Las respiraciones profundas y poderosas definitivamente me dan m\u00e1s energ\u00eda. Intenta inhalar contando hasta 4, exhalar durante 2\u2026","rel":"","context":"En \u00abMMA\u00bb","block_context":{"text":"MMA","link":"https:\/\/blackbeltwhitehat.com\/es\/categoria\/artes-marciales-mixtas\/"},"img":{"alt_text":"increased energy","src":"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2017\/11\/shaman-2897334_960_720.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2017\/11\/shaman-2897334_960_720.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2017\/11\/shaman-2897334_960_720.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2017\/11\/shaman-2897334_960_720.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/posts\/2328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/users\/41980142"}],"replies":[{"embeddable":true,"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/comments?post=2328"}],"version-history":[{"count":1,"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/posts\/2328\/revisions"}],"predecessor-version":[{"id":2329,"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/posts\/2328\/revisions\/2329"}],"wp:attachment":[{"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/media?parent=2328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/categories?post=2328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/tags?post=2328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}