{"id":2685,"date":"2015-04-02T11:13:34","date_gmt":"2015-04-02T11:13:34","guid":{"rendered":"http:\/\/blackbeltwhitehat.com\/?p=2685"},"modified":"2015-04-03T10:48:26","modified_gmt":"2015-04-03T10:48:26","slug":"el-dinero-te-hace-feliz","status":"publish","type":"post","link":"https:\/\/blackbeltwhitehat.com\/es\/2015\/04\/02\/el-dinero-te-hace-feliz\/","title":{"rendered":"\u00bfEl dinero te hace feliz?"},"content":{"rendered":"<p><strong>No:<\/strong><\/p>\n<p>Johnny Depp <span class=\"bqstart\">\u201c\u00a0<\/span>Ha mencionado sus batallas con la ansiedad y la depresi\u00f3n en el pasado.<span class=\"bqend\">\u00a0\u201d<\/span><\/p>\n<p><span class=\"bqstart\"><b><a href=\"http:\/\/www.imdb.com\/name\/nm0000213\/\">Winona Ryder<\/a><\/b> \u201c\u00a0<\/span>Winona Ryder, una de las actrices m\u00e1s famosas de los a\u00f1os 80 y 90, dice que tuvo ataques de p\u00e1nico a partir de los 12 a\u00f1os y termin\u00f3 en una cl\u00ednica psiqui\u00e1trica a los 19 para recibir tratamiento por depresi\u00f3n severa.<span class=\"bqend\">\u00a0\u201d<\/span><\/p>\n<p><span class=\"bqstart\">Juan Cleese \u201c\u00a0<\/span>La leyenda de la comedia John Cleese ha revelado su batalla contra la depresi\u00f3n de toda la vida.<span class=\"bqend\">\u00a0\u201d<\/span><\/p>\n<p>Jim Carrey <span class=\"bqstart\">\u201c\u00a0<\/span>Luch\u00f3 contra una depresi\u00f3n intensa.<span class=\"bqend\">\u00a0\u201d<\/span><\/p>\n<p>Sheryl Crow <span class=\"bqstart\">\u201c\u00a0<\/span>Sufre depresi\u00f3n cr\u00f3nica.<span class=\"bqend\">\u00a0\u201d<\/span><\/p>\n<p>El mega rico de la pel\u00edcula &quot;Foxcatcher&quot;. Totalmente loco, nada feliz, posiblemente porque su madre desaprobaba su obsesi\u00f3n por la lucha libre.<\/p>\n<figure id=\"attachment_2805\" aria-describedby=\"caption-attachment-2805\" style=\"width: 300px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/foxcatcher1.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2805\" data-permalink=\"https:\/\/blackbeltwhitehat.com\/es\/2015\/04\/02\/el-dinero-te-hace-feliz\/foxcatcher1\/\" data-orig-file=\"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/foxcatcher1.jpg?fit=2500%2C1600&amp;ssl=1\" data-orig-size=\"2500,1600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"foxcatcher1\" data-image-description=\"&lt;p&gt;the fox catcher&lt;\/p&gt;\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/foxcatcher1.jpg?fit=1024%2C655&amp;ssl=1\" class=\"size-medium wp-image-2805\" src=\"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/foxcatcher1.jpg?resize=300%2C192&#038;ssl=1\" alt=\"cazador de zorros\" width=\"300\" height=\"192\" \/><\/a><figcaption id=\"caption-attachment-2805\" class=\"wp-caption-text\">flavorwire.com<\/figcaption><\/figure>\n<p>No estoy muy seguro de qu\u00e9 causa la depresi\u00f3n. He le\u00eddo que puede ser gen\u00e9tica, relacionada con la &quot;perspectiva global&quot; del mundo que uno se forma entre los 4 y los 8 a\u00f1os, o incluso con un alto nivel de inflamaci\u00f3n o niveles bajos de testosterona.<\/p>\n<p>No estoy muy seguro, pero el dinero no soluciona el problema. Practicar la gratitud, no compararte con los dem\u00e1s, ni tu casa, coche ni sueldo; la meditaci\u00f3n y el ejercicio ayudan con la depresi\u00f3n leve\u2026 algo que investigar\u00e9 y sobre lo que escribir\u00e9.<br \/>\nRecibir algo de amor incondicional de tus amigos y familiares ciertamente tampoco hace da\u00f1o\u2026<\/p>\n<p>\u2018&#039;La teor\u00eda&#039; es que mientras tengas comida, refugio, amor y algunas otras cosas descritas en la imagen de abajo, <em>poder<\/em> S\u00e9 feliz. Obviamente, las personas con mayor estr\u00e9s, ansiedad y problemas de salud mental son diferentes, pero para el 90% de nosotros\u2026 <a href=\"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/maslow.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2809\" data-permalink=\"https:\/\/blackbeltwhitehat.com\/es\/2015\/04\/02\/el-dinero-te-hace-feliz\/maslow\/\" data-orig-file=\"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/maslow.jpg?fit=960%2C741&amp;ssl=1\" data-orig-size=\"960,741\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"maslow\" data-image-description=\"&lt;p&gt;hierarchy&lt;\/p&gt;\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/maslow.jpg?fit=960%2C741&amp;ssl=1\" class=\"alignnone wp-image-2809 size-large\" src=\"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/maslow.jpg?resize=640%2C494&#038;ssl=1\" alt=\"jerarqu\u00eda de necesidades\" width=\"640\" height=\"494\" \/><\/a><\/p>\n<p><strong>99 problemas \u2013 Cada uno tiene 3<\/strong><br \/>\nUna vez escuch\u00e9 a alguien en el trabajo (no donde trabajo actualmente) quejarse agresivamente del impuesto de circulaci\u00f3n de su Bentley y Range Rover. Hab\u00eda ira y miedo genuinos en su queja.<\/p>\n<p>Esto me ha llevado a concluir que, independientemente de sus ingresos o estilo de vida, todos tienen un problema &quot;importante&quot; que parece el fin del mundo, un problema &quot;mediano&quot; que los molesta y un problema peque\u00f1o y molesto.<\/p>\n<p>La gente buscar\u00e1 activamente estos problemas para satisfacer su necesidad de quejarse y sentirse insatisfecha. Sin \u00e1nimo de trivializarlo, si vives en Sud\u00e1n, tu mayor problema podr\u00eda ser intentar pasar el d\u00eda sin que el LRA te dispare o torture; tu problema medio podr\u00eda ser conseguir agua potable ese d\u00eda, y el problema molesto podr\u00eda ser la enorme hinchaz\u00f3n de est\u00f3mago causada por los par\u00e1sitos en el agua que est\u00e1s bebiendo. (No conozco Sud\u00e1n a fondo, as\u00ed que pido disculpas si no es del todo exacto).<\/p>\n<p>Si vives en el Reino Unido, tu mayor problema podr\u00eda ser el aparcamiento del vecino o tener una casa de solo tres habitaciones que no est\u00e1 tan bien decorada como la de tus amigos (este es el tipo de problema que surge cuando no tienes aficiones o sales mucho); tu problema mediano podr\u00eda ser perder grasa abdominal; y tu problema molesto podr\u00eda ser no poder comprarte un coche nuevo: \u2018Problemas del primer mundo\u2019; sin perspectiva. Esto deber\u00eda ayudarte un poco a ver las cosas desde otra perspectiva: <a href=\"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/carl-sagan.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2810\" data-permalink=\"https:\/\/blackbeltwhitehat.com\/es\/2015\/04\/02\/el-dinero-te-hace-feliz\/carl-sagan\/\" data-orig-file=\"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/carl-sagan.jpg?fit=500%2C500&amp;ssl=1\" data-orig-size=\"500,500\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"carl-sagan\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/carl-sagan.jpg?fit=500%2C500&amp;ssl=1\" class=\"alignnone wp-image-2810 size-full\" src=\"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/carl-sagan.jpg?resize=500%2C500&#038;ssl=1\" alt=\"Carl Sagan\" width=\"500\" height=\"500\" \/><\/a><\/p>\n<p>Pi\u00e9nsalo... por eso la se\u00f1ora mayor del supermercado se pone como loca cuando el dependiente no acepta sus cupones. Probablemente tenga nietos que no la visitan y unos hijos adultos muy ocupados que no pueden dedicarle ni 30 minutos a la semana a tomar una taza de t\u00e9 y charlar. Solo tiene sus cupones. Es su mayor tesoro, y ahora que se los niegan, son su mayor problema.<\/p>\n<p>Lo mismo ocurre con algunas personas ricas: todos los dem\u00e1s problemas potenciales se eliminan con el dinero, por lo que buscan algo m\u00e1s\u2026 desean una casa nueva, encuentran defectos en su c\u00f3nyuge o sus hijos que realmente no existen\u2026 cuando en realidad tienen todo lo que necesitan para ser felices.<\/p>\n<p>Aparentemente, esta cita es falsa (es decir, no proviene del Buda principal), pero aun as\u00ed es interesante y relevante. Deja de desear y empieza a mostrar gratitud.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/buddha.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2814\" data-permalink=\"https:\/\/blackbeltwhitehat.com\/es\/2015\/04\/02\/el-dinero-te-hace-feliz\/buddha\/\" data-orig-file=\"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/buddha.jpg?fit=980%2C3133&amp;ssl=1\" data-orig-size=\"980,3133\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"buddha\" data-image-description=\"&lt;p&gt;buddha&lt;\/p&gt;\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/buddha.jpg?fit=320%2C1024&amp;ssl=1\" class=\"alignnone wp-image-2814 size-full\" src=\"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/buddha.jpg?resize=980%2C3133&#038;ssl=1\" alt=\"quiero felicidad\" width=\"980\" height=\"3133\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Nope: Johnny Depp \u201c\u00a0Has mentioned his battles with anxiety and depression in the past.\u00a0\u201d Winona Ryder \u201c\u00a0Winona Ryder, one of the most famous actresses of the 1980s and 90s, says she had panic attacks starting at 12 and ended up in a psychiatric clinic at 19 for treatment of severe depression.\u00a0\u201d John Cleese \u201c\u00a0Comedic legend [&hellip;]<\/p>\n","protected":false},"author":41980142,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Does Money Make you Happy?","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2007],"tags":[3252,5551,5004,1417],"class_list":["post-2685","post","type-post","status-publish","format-standard","hentry","category-musings","tag-anxiety","tag-depression","tag-mental-health","tag-money"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Does Money Make you Happy? - Fitness &amp; MMA Blog - BlackBeltWhiteHat.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blackbeltwhitehat.com\/es\/2015\/04\/02\/el-dinero-te-hace-feliz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Does Money Make you Happy? - Fitness &amp; MMA Blog - BlackBeltWhiteHat.com\" \/>\n<meta property=\"og:description\" content=\"Nope: Johnny Depp \u201c\u00a0Has mentioned his battles with anxiety and depression in the past.\u00a0\u201d Winona Ryder \u201c\u00a0Winona Ryder, one of the most famous actresses of the 1980s and 90s, says she had panic attacks starting at 12 and ended up in a psychiatric clinic at 19 for treatment of severe depression.\u00a0\u201d John Cleese \u201c\u00a0Comedic legend [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blackbeltwhitehat.com\/es\/2015\/04\/02\/el-dinero-te-hace-feliz\/\" \/>\n<meta property=\"og:site_name\" content=\"Fitness &amp; MMA Blog - BlackBeltWhiteHat.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BlackBeltWhiteHat\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-02T11:13:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-04-03T10:48:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/foxcatcher1.jpg?w=300\" \/>\n<meta name=\"author\" content=\"Dave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MMATraining1980\" \/>\n<meta name=\"twitter:site\" content=\"@MMATraining1980\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dave\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Does Money Make you Happy? - Fitness &amp; MMA Blog - BlackBeltWhiteHat.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blackbeltwhitehat.com\/es\/2015\/04\/02\/el-dinero-te-hace-feliz\/","og_locale":"es_ES","og_type":"article","og_title":"Does Money Make you Happy? - Fitness &amp; MMA Blog - BlackBeltWhiteHat.com","og_description":"Nope: Johnny Depp \u201c\u00a0Has mentioned his battles with anxiety and depression in the past.\u00a0\u201d Winona Ryder \u201c\u00a0Winona Ryder, one of the most famous actresses of the 1980s and 90s, says she had panic attacks starting at 12 and ended up in a psychiatric clinic at 19 for treatment of severe depression.\u00a0\u201d John Cleese \u201c\u00a0Comedic legend [&hellip;]","og_url":"https:\/\/blackbeltwhitehat.com\/es\/2015\/04\/02\/el-dinero-te-hace-feliz\/","og_site_name":"Fitness &amp; MMA Blog - BlackBeltWhiteHat.com","article_publisher":"https:\/\/www.facebook.com\/BlackBeltWhiteHat\/","article_published_time":"2015-04-02T11:13:34+00:00","article_modified_time":"2015-04-03T10:48:26+00:00","og_image":[{"url":"https:\/\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/foxcatcher1.jpg?w=300","type":"","width":"","height":""}],"author":"Dave","twitter_card":"summary_large_image","twitter_creator":"@MMATraining1980","twitter_site":"@MMATraining1980","twitter_misc":{"Escrito por":"Dave","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blackbeltwhitehat.com\/2015\/04\/02\/does-money-make-you-happy\/#article","isPartOf":{"@id":"https:\/\/blackbeltwhitehat.com\/2015\/04\/02\/does-money-make-you-happy\/"},"author":{"name":"Dave","@id":"https:\/\/blackbeltwhitehat.com\/en\/#\/schema\/person\/f009f75d478333ab9af4d98d1c2d03bd"},"headline":"Does Money Make you Happy?","datePublished":"2015-04-02T11:13:34+00:00","dateModified":"2015-04-03T10:48:26+00:00","mainEntityOfPage":{"@id":"https:\/\/blackbeltwhitehat.com\/2015\/04\/02\/does-money-make-you-happy\/"},"wordCount":655,"commentCount":0,"publisher":{"@id":"https:\/\/blackbeltwhitehat.com\/en\/#organization"},"image":{"@id":"https:\/\/blackbeltwhitehat.com\/2015\/04\/02\/does-money-make-you-happy\/#primaryimage"},"thumbnailUrl":"https:\/\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/foxcatcher1.jpg?w=300","keywords":["anxiety","depression","mental health","money"],"articleSection":["Musings"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blackbeltwhitehat.com\/2015\/04\/02\/does-money-make-you-happy\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blackbeltwhitehat.com\/2015\/04\/02\/does-money-make-you-happy\/","url":"https:\/\/blackbeltwhitehat.com\/2015\/04\/02\/does-money-make-you-happy\/","name":"Does Money Make you Happy? - Fitness &amp; MMA Blog - BlackBeltWhiteHat.com","isPartOf":{"@id":"https:\/\/blackbeltwhitehat.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blackbeltwhitehat.com\/2015\/04\/02\/does-money-make-you-happy\/#primaryimage"},"image":{"@id":"https:\/\/blackbeltwhitehat.com\/2015\/04\/02\/does-money-make-you-happy\/#primaryimage"},"thumbnailUrl":"https:\/\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/foxcatcher1.jpg?w=300","datePublished":"2015-04-02T11:13:34+00:00","dateModified":"2015-04-03T10:48:26+00:00","breadcrumb":{"@id":"https:\/\/blackbeltwhitehat.com\/2015\/04\/02\/does-money-make-you-happy\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blackbeltwhitehat.com\/2015\/04\/02\/does-money-make-you-happy\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blackbeltwhitehat.com\/2015\/04\/02\/does-money-make-you-happy\/#primaryimage","url":"https:\/\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/foxcatcher1.jpg?w=300","contentUrl":"https:\/\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/04\/foxcatcher1.jpg?w=300"},{"@type":"BreadcrumbList","@id":"https:\/\/blackbeltwhitehat.com\/2015\/04\/02\/does-money-make-you-happy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blackbeltwhitehat.com\/"},{"@type":"ListItem","position":2,"name":"Does Money Make you Happy?"}]},{"@type":"WebSite","@id":"https:\/\/blackbeltwhitehat.com\/en\/#website","url":"https:\/\/blackbeltwhitehat.com\/en\/","name":"Blog de fitness y MMA - BlackBeltWhiteHat.com","description":"Blog de fitness, MMA y nutrici\u00f3n del Reino Unido","publisher":{"@id":"https:\/\/blackbeltwhitehat.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blackbeltwhitehat.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blackbeltwhitehat.com\/en\/#organization","name":"Blog de fitness y MMA - BlackBeltWhiteHat.com","url":"https:\/\/blackbeltwhitehat.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blackbeltwhitehat.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/blackbeltwhitehat.com\/wp-content\/uploads\/2019\/06\/cropped-mmabloglogodis-copy.png","contentUrl":"https:\/\/blackbeltwhitehat.com\/wp-content\/uploads\/2019\/06\/cropped-mmabloglogodis-copy.png","width":352,"height":352,"caption":"Fitness & MMA Blog - BlackBeltWhiteHat.com"},"image":{"@id":"https:\/\/blackbeltwhitehat.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BlackBeltWhiteHat\/","https:\/\/x.com\/MMATraining1980"]},{"@type":"Person","@id":"https:\/\/blackbeltwhitehat.com\/en\/#\/schema\/person\/f009f75d478333ab9af4d98d1c2d03bd","name":"Dave","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e84bb8dd328aa13877039998cc07d77b62f98c8100dba6c4acb436a41e2a08ac?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e84bb8dd328aa13877039998cc07d77b62f98c8100dba6c4acb436a41e2a08ac?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e84bb8dd328aa13877039998cc07d77b62f98c8100dba6c4acb436a41e2a08ac?s=96&d=identicon&r=g","caption":"Dave"},"description":"Explorador del norte de Gales","sameAs":["http:\/\/seoandmma.wordpress.com"],"url":"https:\/\/blackbeltwhitehat.com\/es\/author\/seoandmma\/"}]}},"jetpack_publicize_connections":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p2Sx3t-Hj","jetpack-related-posts":[{"id":6228,"url":"https:\/\/blackbeltwhitehat.com\/es\/2016\/10\/25\/psilocibina-para-la-depresion-y-la-ansiedad\/","url_meta":{"origin":2685,"position":0},"title":"Psilocibina para la depresi\u00f3n y la ansiedad","author":"Dave","date":"octubre 25, 2016","format":false,"excerpt":"https:\/\/youtu.be\/ZHLJVcpnxXI Psicod\u00e9licos y salud mental La psilocibina se encuentra en los &quot;hongos m\u00e1gicos&quot; Advertencia: \u00a1comer hongos equivocados puede ser mortal! Una investigaci\u00f3n de la Facultad de Medicina Johns Hopkins demostr\u00f3 que las personas mostraron un aumento positivo a largo plazo en el estado de \u00e1nimo despu\u00e9s de una sesi\u00f3n controlada con psilocibina. 46 participantes, con una edad promedio de 46 a\u00f1os, recibieron\u2026","rel":"","context":"En \u00abMusings\u00bb","block_context":{"text":"Musings","link":"https:\/\/blackbeltwhitehat.com\/es\/categoria\/reflexiones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/ZHLJVcpnxXI\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7065,"url":"https:\/\/blackbeltwhitehat.com\/es\/2017\/07\/03\/meditacion-con-hongos-de-psilocibina\/","url_meta":{"origin":2685,"position":1},"title":"Hongos de psilocibina y meditaci\u00f3n","author":"Dave","date":"julio 3, 2017","format":false,"excerpt":"La meditaci\u00f3n es una forma de controlar el 'cerebro de chimpanc\u00e9'. Ese peque\u00f1o y molesto bicho que le da sentido a tu vida, lo juzga todo y crea pensamientos negativos autom\u00e1ticos. La meditaci\u00f3n te permite disociarte de los pensamientos y las emociones y simplemente observarlos pasar... Aparecen sustancias qu\u00edmicas psicod\u00e9licas como la psilocibina\u2026","rel":"","context":"En \u00abMMA\u00bb","block_context":{"text":"MMA","link":"https:\/\/blackbeltwhitehat.com\/es\/categoria\/artes-marciales-mixtas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2017\/07\/magicmushroomspreview.png?fit=784%2C1162&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2017\/07\/magicmushroomspreview.png?fit=784%2C1162&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2017\/07\/magicmushroomspreview.png?fit=784%2C1162&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2017\/07\/magicmushroomspreview.png?fit=784%2C1162&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6157,"url":"https:\/\/blackbeltwhitehat.com\/es\/2016\/10\/20\/dieta-para-la-depresion-y-la-ansiedad\/","url_meta":{"origin":2685,"position":2},"title":"Dieta para la depresi\u00f3n y la ansiedad","author":"Dave","date":"octubre 20, 2016","format":false,"excerpt":"https:\/\/youtu.be\/8dfzHaqEuZ4 *Dieta bajo su propia responsabilidad. Solo con fines informativos* La salud intestinal est\u00e1 fuertemente correlacionada con la depresi\u00f3n. Puede leer un estudio interesante aqu\u00ed para obtener m\u00e1s informaci\u00f3n. Una mala salud intestinal provoca inflamaci\u00f3n. Una mala alimentaci\u00f3n tambi\u00e9n puede da\u00f1ar la barrera hematoencef\u00e1lica. Combine ambos y\u2026","rel":"","context":"En \u00abNutrition\u00bb","block_context":{"text":"Nutrition","link":"https:\/\/blackbeltwhitehat.com\/es\/categoria\/nutricion\/"},"img":{"alt_text":"CBD Oil Infographic","src":"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2017\/07\/cbdoilinfographic4.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2017\/07\/cbdoilinfographic4.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2017\/07\/cbdoilinfographic4.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2017\/07\/cbdoilinfographic4.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6193,"url":"https:\/\/blackbeltwhitehat.com\/es\/2016\/10\/24\/suplementacion-de-magnesio-para-la-recuperacion-muscular-tras-la-ansiedad\/","url_meta":{"origin":2685,"position":3},"title":"Suplementaci\u00f3n de magnesio para la ansiedad y la recuperaci\u00f3n muscular","author":"Dave","date":"octubre 24, 2016","format":false,"excerpt":"Ansiedad, tensi\u00f3n en el cuello y dolores de cabeza. Como alguien que ha sufrido durante a\u00f1os dolores de cabeza constantes (problemas del primer mundo), he probado de todo, desde c\u00farcuma hasta aceite de CBD. El aceite de CBD funciona bastante bien, ya que es un relajante muscular eficaz que me ayuda a aliviar la tensi\u00f3n del cuello y\u2026","rel":"","context":"En \u00abFitness\u00bb","block_context":{"text":"Fitness","link":"https:\/\/blackbeltwhitehat.com\/es\/categoria\/aptitud-fisica\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/_UsEM7qbhdc\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2721,"url":"https:\/\/blackbeltwhitehat.com\/es\/2015\/03\/06\/ejercicio-para-estudios-sobre-la-depresion\/","url_meta":{"origin":2685,"position":4},"title":"Ejercicio para la depresi\u00f3n \u2013 estudios","author":"Dave","date":"marzo 6, 2015","format":false,"excerpt":"Estudio 1 http:\/\/psycnet.apa.org\/journals\/ccp\/55\/5\/748\/ Comparamos la efectividad del ejercicio aer\u00f3bico y el no aer\u00f3bico en el tratamiento de la depresi\u00f3n cl\u00ednica en mujeres. Un total de 40 mujeres, evaluadas seg\u00fan los Criterios Diagn\u00f3sticos de Investigaci\u00f3n para el trastorno depresivo mayor o menor, fueron asignadas aleatoriamente a un programa de 8 semanas de carrera (aer\u00f3bico), levantamiento de pesas (no aer\u00f3bico) o lista de espera\u2026","rel":"","context":"En \u00abFitness\u00bb","block_context":{"text":"Fitness","link":"https:\/\/blackbeltwhitehat.com\/es\/categoria\/aptitud-fisica\/"},"img":{"alt_text":"running mental health","src":"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/03\/running.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6293,"url":"https:\/\/blackbeltwhitehat.com\/es\/2017\/01\/02\/suplementos-para-la-ansiedad-por-estres\/","url_meta":{"origin":2685,"position":5},"title":"Suplementos para el estr\u00e9s y la ansiedad","author":"Dave","date":"enero 2, 2017","format":false,"excerpt":"He notado un patr\u00f3n \u00faltimamente: cualquier hombre de mediana edad con buena dentadura que conozco y con el que entablo conversaci\u00f3n, siempre me pregunta c\u00f3mo lidiar con el estr\u00e9s y la ansiedad. Con esto en mente, pens\u00e9 en escribir una entrada en el blog para satisfacer la aparente demanda de esta informaci\u00f3n. Dieta, dieta, dieta\u2026","rel":"","context":"En \u00abanxiety\u00bb","block_context":{"text":"anxiety","link":"https:\/\/blackbeltwhitehat.com\/es\/etiqueta\/ansiedad\/"},"img":{"alt_text":"ashwaganda","src":"https:\/\/i0.wp.com\/blackbeltwhitehat.com\/wp-content\/uploads\/2015\/09\/ashwagandha-elixir-par-excellence.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/posts\/2685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/users\/41980142"}],"replies":[{"embeddable":true,"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/comments?post=2685"}],"version-history":[{"count":9,"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/posts\/2685\/revisions"}],"predecessor-version":[{"id":2817,"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/posts\/2685\/revisions\/2817"}],"wp:attachment":[{"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/media?parent=2685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/categories?post=2685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blackbeltwhitehat.com\/es\/wp-json\/wp\/v2\/tags?post=2685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}